{"id":3416,"date":"2021-03-18T23:26:08","date_gmt":"2021-03-18T23:26:08","guid":{"rendered":"https:\/\/rgmed.com\/?post_type=product&#038;p=3416"},"modified":"2022-07-12T16:24:10","modified_gmt":"2022-07-12T16:24:10","slug":"espanol-insuflador-de-alto-flujo-de-40-litros","status":"publish","type":"product","link":"https:\/\/rgmed.com\/de\/products\/urology\/01-cameras-equipment-accesories\/espanol-insuflador-de-alto-flujo-de-40-litros\/","title":{"rendered":"Highflow 40 Liter insufflator"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":3888,"template":"","meta":[],"product_brand":[],"product_cat":[225,265,342],"product_tag":[],"class_list":{"0":"post-3416","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-01-cameras-equipment-accesories","7":"product_cat-urology","8":"product_cat-equipement-cameras","10":"first","11":"instock","12":"shipping-taxable","13":"purchasable","14":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Highflow 40 Liter insufflator - Rg Medical<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/rgmed.com\/products\/urology\/01-cameras-equipment-accesories\/espanol-insuflador-de-alto-flujo-de-40-litros\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Highflow 40 Liter insufflator - Rg Medical\" \/>\n<meta property=\"og:url\" content=\"https:\/\/rgmed.com\/products\/urology\/01-cameras-equipment-accesories\/espanol-insuflador-de-alto-flujo-de-40-litros\/\" \/>\n<meta property=\"og:site_name\" content=\"Rg Medical\" \/>\n<meta property=\"article:modified_time\" content=\"2022-07-12T16:24:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/rgmed.com\/wp-content\/uploads\/2021\/03\/insuflador-nueo-jpg.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1115\" \/>\n\t<meta property=\"og:image:height\" content=\"876\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/rgmed.com\/products\/urology\/01-cameras-equipment-accesories\/espanol-insuflador-de-alto-flujo-de-40-litros\/\",\"url\":\"https:\/\/rgmed.com\/products\/urology\/01-cameras-equipment-accesories\/espanol-insuflador-de-alto-flujo-de-40-litros\/\",\"name\":\"Highflow 40 Liter insufflator - Rg Medical\",\"isPartOf\":{\"@id\":\"https:\/\/rgmed.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/rgmed.com\/products\/urology\/01-cameras-equipment-accesories\/espanol-insuflador-de-alto-flujo-de-40-litros\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/rgmed.com\/products\/urology\/01-cameras-equipment-accesories\/espanol-insuflador-de-alto-flujo-de-40-litros\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/rgmed.com\/wp-content\/uploads\/2021\/03\/insuflador-nueo-jpg.jpg\",\"datePublished\":\"2021-03-18T23:26:08+00:00\",\"dateModified\":\"2022-07-12T16:24:10+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/rgmed.com\/products\/urology\/01-cameras-equipment-accesories\/espanol-insuflador-de-alto-flujo-de-40-litros\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/rgmed.com\/products\/urology\/01-cameras-equipment-accesories\/espanol-insuflador-de-alto-flujo-de-40-litros\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/rgmed.com\/products\/urology\/01-cameras-equipment-accesories\/espanol-insuflador-de-alto-flujo-de-40-litros\/#primaryimage\",\"url\":\"https:\/\/rgmed.com\/wp-content\/uploads\/2021\/03\/insuflador-nueo-jpg.jpg\",\"contentUrl\":\"https:\/\/rgmed.com\/wp-content\/uploads\/2021\/03\/insuflador-nueo-jpg.jpg\",\"width\":1115,\"height\":876},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/rgmed.com\/products\/urology\/01-cameras-equipment-accesories\/espanol-insuflador-de-alto-flujo-de-40-litros\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Products\",\"item\":\"https:\/\/rgmed.com\/products\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Insuflador de alto flujo 40L\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/rgmed.com\/#website\",\"url\":\"https:\/\/rgmed.com\/\",\"name\":\"Rg Medical\",\"description\":\"(English) Finest Quality Precision Surgical Instruments\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/rgmed.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Highflow 40 Liter insufflator - Rg Medical","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/rgmed.com\/products\/urology\/01-cameras-equipment-accesories\/espanol-insuflador-de-alto-flujo-de-40-litros\/","og_locale":"de_DE","og_type":"article","og_title":"Highflow 40 Liter insufflator - Rg Medical","og_url":"https:\/\/rgmed.com\/products\/urology\/01-cameras-equipment-accesories\/espanol-insuflador-de-alto-flujo-de-40-litros\/","og_site_name":"Rg Medical","article_modified_time":"2022-07-12T16:24:10+00:00","og_image":[{"width":1115,"height":876,"url":"https:\/\/rgmed.com\/wp-content\/uploads\/2021\/03\/insuflador-nueo-jpg.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/rgmed.com\/products\/urology\/01-cameras-equipment-accesories\/espanol-insuflador-de-alto-flujo-de-40-litros\/","url":"https:\/\/rgmed.com\/products\/urology\/01-cameras-equipment-accesories\/espanol-insuflador-de-alto-flujo-de-40-litros\/","name":"Highflow 40 Liter insufflator - Rg Medical","isPartOf":{"@id":"https:\/\/rgmed.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/rgmed.com\/products\/urology\/01-cameras-equipment-accesories\/espanol-insuflador-de-alto-flujo-de-40-litros\/#primaryimage"},"image":{"@id":"https:\/\/rgmed.com\/products\/urology\/01-cameras-equipment-accesories\/espanol-insuflador-de-alto-flujo-de-40-litros\/#primaryimage"},"thumbnailUrl":"https:\/\/rgmed.com\/wp-content\/uploads\/2021\/03\/insuflador-nueo-jpg.jpg","datePublished":"2021-03-18T23:26:08+00:00","dateModified":"2022-07-12T16:24:10+00:00","breadcrumb":{"@id":"https:\/\/rgmed.com\/products\/urology\/01-cameras-equipment-accesories\/espanol-insuflador-de-alto-flujo-de-40-litros\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/rgmed.com\/products\/urology\/01-cameras-equipment-accesories\/espanol-insuflador-de-alto-flujo-de-40-litros\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/rgmed.com\/products\/urology\/01-cameras-equipment-accesories\/espanol-insuflador-de-alto-flujo-de-40-litros\/#primaryimage","url":"https:\/\/rgmed.com\/wp-content\/uploads\/2021\/03\/insuflador-nueo-jpg.jpg","contentUrl":"https:\/\/rgmed.com\/wp-content\/uploads\/2021\/03\/insuflador-nueo-jpg.jpg","width":1115,"height":876},{"@type":"BreadcrumbList","@id":"https:\/\/rgmed.com\/products\/urology\/01-cameras-equipment-accesories\/espanol-insuflador-de-alto-flujo-de-40-litros\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Products","item":"https:\/\/rgmed.com\/products\/"},{"@type":"ListItem","position":2,"name":"Insuflador de alto flujo 40L"}]},{"@type":"WebSite","@id":"https:\/\/rgmed.com\/#website","url":"https:\/\/rgmed.com\/","name":"Rg Medical","description":"(English) Finest Quality Precision Surgical Instruments","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/rgmed.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/rgmed.com\/de\/wp-json\/wp\/v2\/product\/3416","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rgmed.com\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/rgmed.com\/de\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rgmed.com\/de\/wp-json\/wp\/v2\/media\/3888"}],"wp:attachment":[{"href":"https:\/\/rgmed.com\/de\/wp-json\/wp\/v2\/media?parent=3416"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/rgmed.com\/de\/wp-json\/wp\/v2\/product_brand?post=3416"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/rgmed.com\/de\/wp-json\/wp\/v2\/product_cat?post=3416"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/rgmed.com\/de\/wp-json\/wp\/v2\/product_tag?post=3416"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}